{"id":58,"count":1,"description":"","link":"https:\/\/nomadheat.com\/nl\/blog\/tag\/overlanding\/","name":"overlanding","slug":"overlanding","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>overlanding Archives | NomadHeat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nomadheat.com\/nl\/blog\/tag\/overlanding\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"overlanding Archives | NomadHeat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nomadheat.com\/nl\/blog\/tag\/overlanding\/\" \/>\n<meta property=\"og:site_name\" content=\"NomadHeat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/nomadheat.com\\\/nb\\\/blogg\\\/tag\\\/overlanding\\\/\",\"url\":\"https:\\\/\\\/nomadheat.com\\\/nb\\\/blogg\\\/tag\\\/overlanding\\\/\",\"name\":\"overlanding Archives | NomadHeat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nomadheat.com\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nomadheat.com\\\/nb\\\/blogg\\\/tag\\\/overlanding\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nomadheat.com\\\/nb\\\/blogg\\\/tag\\\/overlanding\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nomadheat.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"overlanding\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nomadheat.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/nomadheat.com\\\/nl\\\/\",\"name\":\"NomadHeat\",\"description\":\"Handmade Wool Sleeping Bags\",\"publisher\":{\"@id\":\"https:\\\/\\\/nomadheat.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nomadheat.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nomadheat.com\\\/nl\\\/#organization\",\"name\":\"Nomad Heat\",\"url\":\"https:\\\/\\\/nomadheat.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/nomadheat.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nomadheat.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/nomadheat.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Nomad Heat\"},\"image\":{\"@id\":\"https:\\\/\\\/nomadheat.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"overlanding Archives | NomadHeat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nomadheat.com\/nl\/blog\/tag\/overlanding\/","og_locale":"nl_NL","og_type":"article","og_title":"overlanding Archives | NomadHeat","og_url":"https:\/\/nomadheat.com\/nl\/blog\/tag\/overlanding\/","og_site_name":"NomadHeat","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nomadheat.com\/nb\/blogg\/tag\/overlanding\/","url":"https:\/\/nomadheat.com\/nb\/blogg\/tag\/overlanding\/","name":"overlanding Archief | NomadHeat","isPartOf":{"@id":"https:\/\/nomadheat.com\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/nomadheat.com\/nb\/blogg\/tag\/overlanding\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/nomadheat.com\/nb\/blogg\/tag\/overlanding\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nomadheat.com\/nl\/"},{"@type":"ListItem","position":2,"name":"overlanding"}]},{"@type":"WebSite","@id":"https:\/\/nomadheat.com\/nl\/#website","url":"https:\/\/nomadheat.com\/nl\/","name":"NomadHeat","description":"Handgemaakte wollen slaapzakken","publisher":{"@id":"https:\/\/nomadheat.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nomadheat.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/nomadheat.com\/nl\/#organization","name":"Nomad warmte","url":"https:\/\/nomadheat.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/nomadheat.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/nomadheat.com\/wp-content\/uploads\/2021\/10\/favicon.png","contentUrl":"https:\/\/nomadheat.com\/wp-content\/uploads\/2021\/10\/favicon.png","width":512,"height":512,"caption":"Nomad Heat"},"image":{"@id":"https:\/\/nomadheat.com\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nomadheat.com\/nl\/wp-json\/wp\/v2\/tags\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nomadheat.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/nomadheat.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/nomadheat.com\/nl\/wp-json\/wp\/v2\/posts?tags=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}